{"id":11150,"date":"2026-05-21T16:25:57","date_gmt":"2026-05-21T14:25:57","guid":{"rendered":"https:\/\/parnassius-apollo.life\/?p=11150"},"modified":"2026-05-21T16:26:02","modified_gmt":"2026-05-21T14:26:02","slug":"life-apollo2020-bei-den-austrian-life-days-2026","status":"publish","type":"post","link":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026","title":{"rendered":"LIFE Apollo2020 bei den Austrian LIFE Days 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Im Rahmen der Replikations- und Disseminationsaktivit\u00e4ten nahm das \u00f6sterreichische Team von LIFE Apollo2020 an den Austrian LIFE Days 2026 teil. Die zweit\u00e4gige Konferenz wurde vom Bundesministerium f\u00fcr Land- und Forstwirtschaft, Klima- und Umweltschutz, Regionen und Wasserwirtschaft (BMLUK) organisiert und brachte mehr als 80 Vertreter:innen von LIFE-Projekten, Ministerien, NGOs, ELMEN, Projektpartnern und Umweltorganisationen zusammen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach den internationalen LIFE-Treffen in Polen und Tschechien setzte LIFE Apollo2020 damit den grenz\u00fcberschreitenden Austausch mit anderen LIFE-Projekten auch in \u00d6sterreich fort. Solche Treffen sind ein wichtiger Bestandteil erfolgreicher LIFE-Arbeit: Sie erm\u00f6glichen nicht nur die Pr\u00e4sentation eigener Projektergebnisse, sondern auch den direkten Austausch \u00fcber praktische Erfahrungen, neue Herausforderungen, Finanz- und Berichtspflichten, Monitoring, \u00d6ffentlichkeitsarbeit und langfristige Wirkung von Naturschutzma\u00dfnahmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er\u00f6ffnet wurde die Konferenz unter anderem von DIin Daniela K\u00f6nig, Direktorin der Direktion Umwelt und Wasserwirtschaft des Landes Ober\u00f6sterreich, Mag. Gerd Frik von VERBUND Hydro Power GmbH sowie DI Gottfried Lamers vom BMLUK, Sektion VI\/7 \u2013 Klima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LIFE Apollo2020 hatte die besondere Ehre, die Projektsession der Konferenz zu er\u00f6ffnen. Anni Henning von der European Wilderness Society stellte dabei die laufenden Ma\u00dfnahmen zur Erhaltung der Apollo-Schmetterlingspopulationen in drei EU-Regionen \u2013 Polen, Tschechien und \u00d6sterreich \u2013 vor. Auch das Projekt stockProtect wurde durch Anni Henning pr\u00e4sentiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Rahmen der Austrian LIFE Days wurden zahlreiche nationale und internationale LIFE-Projekte und Initiativen vorgestellt, darunter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>LIFEstockProtect \u2013 Improving livestock protection for the direct benefit of wolf conservation in the German-speaking Alpine Region<\/li>\n\n\n\n<li>LIFE Apollo2020 \u2013 Erhaltung der Apollo-Schmetterlingspopulationen in drei EU-Regionen<\/li>\n\n\n\n<li>impaQt \u2013 climate-resilient cities: cross-siloed impact of urban city quarters<\/li>\n\n\n\n<li>EnCAM \u2013 Adapting large-scale environmental projects to climate change while supporting climate objectives<\/li>\n\n\n\n<li>EmpowerLIFE \u2013 Empowering local communities to co-create and implement DIY climate solutions<\/li>\n\n\n\n<li>Living River Lahn \u2013 one river, many interests<\/li>\n\n\n\n<li>LIFE RESTORE for MDD \u2013 Preserving and restoring floodplain forest habitats along the Mura-Drava-Danube rivers<\/li>\n\n\n\n<li>LIFE Boat 4 Sturgeon \u2013 Boat to rescue four Danube sturgeon species from extinction<\/li>\n\n\n\n<li>Riverscape Lower Inn \u2013 An ecological perspective for riverscape management in the floodplains of the Lower Inn<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ein besonders wichtiger Programmpunkt war der Beitrag von Felix Bergmann von ELMEN zum Projektmonitoring 2026. ELMEN stellte dabei aktuelle Informationen zu Monitoring, Finanzregeln und administrativen Anforderungen vor und stand den LIFE-Projekten f\u00fcr konkrete Fragen zur Verf\u00fcgung. Gerade dieser direkte Austausch ist f\u00fcr die Umsetzung von LIFE-Projekten von gro\u00dfer Bedeutung, da rechtzeitige Kl\u00e4rungen zu Finanz- und Berichtspflichten wesentlich zur Qualit\u00e4t, Transparenz und erfolgreichen Projektabwicklung beitragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Exkursion f\u00fchrte zur im Sommer 2024 fertiggestellten Fischwanderhilfe am Innkraftwerk Braunau-Simbach sowie zu angrenzenden Fl\u00e4chen des LIFE-Projekts Riverscape Lower Inn. Dort wurden Ma\u00dfnahmen zur Wiederherstellung der Durchg\u00e4ngigkeit, zur Schaffung neuer Flie\u00dfgew\u00e4sserlebensr\u00e4ume, Kiesb\u00e4nke, Reproduktionsfl\u00e4chen und Aufwuchshabitate sowie zur Entwicklung hochwertiger Wiesenlebensr\u00e4ume vorgestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend der Exkursion bestand gro\u00dfes Interesse an den Erfahrungen aus LIFE Apollo2020 zur naturnahen Pflege von Offenlandlebensr\u00e4umen durch Beweidung. Besonders diskutiert wurde, wie Ziegen zur Entbuschung von Deichen und B\u00f6schungen eingesetzt werden k\u00f6nnen, um schmetterlingsfreundliche Habitate zu erhalten. Diese Form der gezielten Beweidung kann eine wichtige Alternative zum maschinellen Mulchen darstellen, da Mulchma\u00dfnahmen Eier und Entwicklungsstadien von Schmetterlingen zerst\u00f6ren k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiteres Highlight war der Austausch mit dem neu gestarteten LIFE-Projekt LIFE VienNATURA. Das Projektteam lud das Apollo Austria Team zu einer Besichtigung des Projektgebietes am ehemaligen Verschiebebahnhof Breitenlee in Wien-Donaustadt ein, um m\u00f6gliche Kooperationen und den Erfahrungsaustausch zum Einsatz von Beweidungssystemen f\u00fcr die Wiederherstellung schmetterlingsfreundlicher Lebensr\u00e4ume zu diskutieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LIFE VienNATURA entwickelt auf rund 90 Hektar eine neue Natura-2000-Schutzzone in Wien. Ziel ist die Wiederherstellung seltener Steppenrasen, die Bek\u00e4mpfung invasiver Arten sowie die Schaffung naturnaher Weidelandschaften mit Schafen und Ziegen zur F\u00f6rderung der Biodiversit\u00e4t.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Austrian LIFE Days 2026 haben einmal mehr gezeigt, wie wichtig der Austausch zwischen LIFE-Projekten ist. Die Herausforderungen im Natur- und Klimaschutz sind vielf\u00e4ltig, doch viele L\u00f6sungsans\u00e4tze lassen sich \u00fcbertragen, weiterentwickeln und gemeinsam st\u00e4rken. F\u00fcr LIFE Apollo2020 sind solche Treffen daher ein zentraler Beitrag zu Replikation, Dissemination und langfristiger Zusammenarbeit innerhalb des europ\u00e4ischen LIFE-Netzwerks.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.78614%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11170\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5711\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778061750&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"LIFEdays 2026_5711\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a01 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11170\" data-link=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5711\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5711-1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.21386%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11169\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5713\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778061831&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"LIFEdays 2026_5713\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a02 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11169\" data-link=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5713\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5713-1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11168\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5715\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?fit=4032%2C3024&amp;ssl=1\" data-orig-size=\"4032,3024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778061905&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"LIFEdays 2026_5715\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?fit=4032%2C3024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a03 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"3024\" data-id=\"11168\" data-link=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5715\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg\" data-width=\"4032\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5715-1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11167\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5717\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778062623&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"LIFEdays 2026_5717\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a04 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11167\" data-link=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5717\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5717-1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11166\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5721\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?fit=4032%2C3024&amp;ssl=1\" data-orig-size=\"4032,3024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778068009&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"LIFEdays 2026_5721\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?fit=4032%2C3024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a05 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"3024\" data-id=\"11166\" data-link=\"https:\/\/parnassius-apollo.life\/de\/lifedays-2026_5721\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg\" data-width=\"4032\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/LIFEdays-2026_5721-1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11163\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5711\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778061750&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5711\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a06 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11163\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5711\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5711.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.21386%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11162\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5713\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778061831&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5713\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a07 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11162\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5713\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5713.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11161\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5715\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?fit=4032%2C3024&amp;ssl=1\" data-orig-size=\"4032,3024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778061905&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5715\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?fit=4032%2C3024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a08 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"3024\" data-id=\"11161\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5715\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg\" data-width=\"4032\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5715.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.78614%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11160\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5717\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778062623&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5717\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a09 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11160\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5717\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5717.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11159\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5721\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?fit=4032%2C3024&amp;ssl=1\" data-orig-size=\"4032,3024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778068009&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5721\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?fit=4032%2C3024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a010 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"3024\" data-id=\"11159\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5721\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg\" data-width=\"4032\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5721.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11158\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5732\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778086828&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.2200000286119&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.0013623978201635&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5732\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a011 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11158\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5732\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5732.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.78614%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11157\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5733\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778089213&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0048780487804878&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5733\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a012 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11157\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5733\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5733.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.21386%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11156\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/img_5734\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?fit=5712%2C4284&amp;ssl=1\" data-orig-size=\"5712,4284\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.78&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 17 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778089216&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.7649998656528&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.0011261261261261&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"IMG_5734\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?fit=5712%2C4284&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a013 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"4284\" data-id=\"11156\" data-link=\"https:\/\/parnassius-apollo.life\/de\/img_5734\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg\" data-width=\"5712\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/IMG_5734-1.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"11179\" data-permalink=\"https:\/\/parnassius-apollo.life\/de\/2026-05-life-apollo-img_4572-2\" data-orig-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&amp;ssl=1\" data-orig-size=\"4032,3024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778064106&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.7&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"2026.05 LIFE Apollo IMG_4572\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Bild\u00a014 von 14 im Vollbildmodus \u00f6ffnen\" srcset=\"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"3024\" data-id=\"11179\" data-link=\"https:\/\/parnassius-apollo.life\/de?attachment_id=11179\" data-url=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg\" data-width=\"4032\" src=\"https:\/\/spcdn.shortpixel.ai\/spio\/ret_img,q_cdnize\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen der Replikations- und Disseminationsaktivit\u00e4ten nahm das \u00f6sterreichische Team von LIFE Apollo2020 an den Austrian LIFE Days 2026 teil.<\/p>\n","protected":false},"author":1,"featured_media":11179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[56],"tags":[304,296,57,269,308],"class_list":["post-11150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projekteinblicke","tag-konferenz","tag-lebensraum-restaurierung","tag-osterreich","tag-parnassius-apollo-de","tag-zucht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LIFE Apollo2020 bei den Austrian LIFE Days 2026 - Parnassius apollo project LIFE Apollo2020<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIFE Apollo2020 bei den Austrian LIFE Days 2026\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen der Replikations- und Disseminationsaktivit\u00e4ten nahm das \u00f6sterreichische Team von LIFE Apollo2020 an den Austrian LIFE Days 2026 teil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026\" \/>\n<meta property=\"og:site_name\" content=\"Parnassius apollo project LIFE Apollo2020\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-21T14:25:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T14:26:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Max A E Rossberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Max A E Rossberg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026\"},\"author\":{\"name\":\"Max A E Rossberg\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#\\\/schema\\\/person\\\/db18db89ffe956aaa9b354ea3a358595\"},\"headline\":\"LIFE Apollo2020 bei den Austrian LIFE Days 2026\",\"datePublished\":\"2026-05-21T14:25:57+00:00\",\"dateModified\":\"2026-05-21T14:26:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/parnassius-apollo.life\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1\",\"keywords\":[\"Konferenz\",\"Lebensraum-Restaurierung\",\"\u00d6sterreich\",\"Parnassius Apollo\",\"Zucht\"],\"articleSection\":[\"Projekteinblicke\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026\",\"url\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026\",\"name\":\"LIFE Apollo2020 bei den Austrian LIFE Days 2026 - Parnassius apollo project LIFE Apollo2020\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/parnassius-apollo.life\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1\",\"datePublished\":\"2026-05-21T14:25:57+00:00\",\"dateModified\":\"2026-05-21T14:26:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/parnassius-apollo.life\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/parnassius-apollo.life\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1\",\"width\":4032,\"height\":3024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/life-apollo2020-bei-den-austrian-life-days-2026#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIFE Apollo2020 bei den Austrian LIFE Days 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#website\",\"url\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\",\"name\":\"Parnassius apollo project LIFE Apollo2020\",\"description\":\"Conservation of Parnassius apollo in Czechia, Poland and Austria\",\"publisher\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/parnassius-apollo.life\\\/de?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#organization\",\"name\":\"LIFE Apollo 2020\",\"alternateName\":\"Parnassius Apollo LIFE Project\",\"url\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/parnassius-apollo.life\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LIFE_Apollo_Final-e1651506328254.png?fit=127%2C150&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/parnassius-apollo.life\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LIFE_Apollo_Final-e1651506328254.png?fit=127%2C150&ssl=1\",\"width\":127,\"height\":150,\"caption\":\"LIFE Apollo 2020\"},\"image\":{\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#\\\/schema\\\/logo\\\/image\\\/\"},\"email\":\"info@apollo-2020.life\",\"legalName\":\"Karkonoski Park Narodowy\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/parnassius-apollo.life\\\/de#\\\/schema\\\/person\\\/db18db89ffe956aaa9b354ea3a358595\",\"name\":\"Max A E Rossberg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1ba4ca1bcc05f047030d7bd36e2cd2395b444a1ad53d0e598385bfa5da87a79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1ba4ca1bcc05f047030d7bd36e2cd2395b444a1ad53d0e598385bfa5da87a79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1ba4ca1bcc05f047030d7bd36e2cd2395b444a1ad53d0e598385bfa5da87a79?s=96&d=mm&r=g\",\"caption\":\"Max A E Rossberg\"},\"sameAs\":[\"https:\\\/\\\/wilderness-society.org\"],\"url\":\"https:\\\/\\\/parnassius-apollo.life\\\/de\\\/author\\\/max\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LIFE Apollo2020 bei den Austrian LIFE Days 2026 - Parnassius apollo project LIFE Apollo2020","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026","og_locale":"de_DE","og_type":"article","og_title":"LIFE Apollo2020 bei den Austrian LIFE Days 2026","og_description":"Im Rahmen der Replikations- und Disseminationsaktivit\u00e4ten nahm das \u00f6sterreichische Team von LIFE Apollo2020 an den Austrian LIFE Days 2026 teil.","og_url":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026","og_site_name":"Parnassius apollo project LIFE Apollo2020","article_published_time":"2026-05-21T14:25:57+00:00","article_modified_time":"2026-05-21T14:26:02+00:00","og_image":[{"url":"https:\/\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg","width":4032,"height":3024,"type":"image\/jpeg"}],"author":"Max A E Rossberg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Max A E Rossberg","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#article","isPartOf":{"@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026"},"author":{"name":"Max A E Rossberg","@id":"https:\/\/parnassius-apollo.life\/de#\/schema\/person\/db18db89ffe956aaa9b354ea3a358595"},"headline":"LIFE Apollo2020 bei den Austrian LIFE Days 2026","datePublished":"2026-05-21T14:25:57+00:00","dateModified":"2026-05-21T14:26:02+00:00","mainEntityOfPage":{"@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/parnassius-apollo.life\/de#organization"},"image":{"@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1","keywords":["Konferenz","Lebensraum-Restaurierung","\u00d6sterreich","Parnassius Apollo","Zucht"],"articleSection":["Projekteinblicke"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#respond"]}]},{"@type":"WebPage","@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026","url":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026","name":"LIFE Apollo2020 bei den Austrian LIFE Days 2026 - Parnassius apollo project LIFE Apollo2020","isPartOf":{"@id":"https:\/\/parnassius-apollo.life\/de#website"},"primaryImageOfPage":{"@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage"},"image":{"@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1","datePublished":"2026-05-21T14:25:57+00:00","dateModified":"2026-05-21T14:26:02+00:00","breadcrumb":{"@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#primaryimage","url":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1","contentUrl":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1","width":4032,"height":3024},{"@type":"BreadcrumbList","@id":"https:\/\/parnassius-apollo.life\/de\/life-apollo2020-bei-den-austrian-life-days-2026#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/parnassius-apollo.life\/de"},{"@type":"ListItem","position":2,"name":"LIFE Apollo2020 bei den Austrian LIFE Days 2026"}]},{"@type":"WebSite","@id":"https:\/\/parnassius-apollo.life\/de#website","url":"https:\/\/parnassius-apollo.life\/de","name":"Parnassius apollo project LIFE Apollo2020","description":"Conservation of Parnassius apollo in Czechia, Poland and Austria","publisher":{"@id":"https:\/\/parnassius-apollo.life\/de#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parnassius-apollo.life\/de?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/parnassius-apollo.life\/de#organization","name":"LIFE Apollo 2020","alternateName":"Parnassius Apollo LIFE Project","url":"https:\/\/parnassius-apollo.life\/de","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/parnassius-apollo.life\/de#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2022\/05\/LIFE_Apollo_Final-e1651506328254.png?fit=127%2C150&ssl=1","contentUrl":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2022\/05\/LIFE_Apollo_Final-e1651506328254.png?fit=127%2C150&ssl=1","width":127,"height":150,"caption":"LIFE Apollo 2020"},"image":{"@id":"https:\/\/parnassius-apollo.life\/de#\/schema\/logo\/image\/"},"email":"info@apollo-2020.life","legalName":"Karkonoski Park Narodowy","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/parnassius-apollo.life\/de#\/schema\/person\/db18db89ffe956aaa9b354ea3a358595","name":"Max A E Rossberg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a1ba4ca1bcc05f047030d7bd36e2cd2395b444a1ad53d0e598385bfa5da87a79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1ba4ca1bcc05f047030d7bd36e2cd2395b444a1ad53d0e598385bfa5da87a79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1ba4ca1bcc05f047030d7bd36e2cd2395b444a1ad53d0e598385bfa5da87a79?s=96&d=mm&r=g","caption":"Max A E Rossberg"},"sameAs":["https:\/\/wilderness-society.org"],"url":"https:\/\/parnassius-apollo.life\/de\/author\/max"}]}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/parnassius-apollo.life\/wp-content\/uploads\/2026\/05\/2026.05-LIFE-Apollo-IMG_4572.jpg?fit=4032%2C3024&ssl=1","_links":{"self":[{"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/posts\/11150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/comments?post=11150"}],"version-history":[{"count":2,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/posts\/11150\/revisions"}],"predecessor-version":[{"id":11185,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/posts\/11150\/revisions\/11185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/media\/11179"}],"wp:attachment":[{"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/media?parent=11150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/categories?post=11150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parnassius-apollo.life\/de\/wp-json\/wp\/v2\/tags?post=11150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}